{"id":2341,"count":1,"description":"","link":"https:\/\/www.barragrande24horas.com.br\/v1\/tag\/fala-de-rui-costa-para-que-cidades-sem-covid-19-nao-adotem-medidas-restritivas-causa-revolta-dos-prefeitos\/","name":"Fala de Rui Costa para que cidades sem COVID-19 n\u00e3o adotem medidas restritivas causa revolta dos prefeitos","slug":"fala-de-rui-costa-para-que-cidades-sem-covid-19-nao-adotem-medidas-restritivas-causa-revolta-dos-prefeitos","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags\/2341"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts?tags=2341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}