{"id":1751,"count":1,"description":"","link":"https:\/\/www.barragrande24horas.com.br\/v1\/tag\/prefeitura-de-marau-continua-com-equipes-removendo-pelotas-de-oleo-nas-praias-com-apoio-das-comunidades\/","name":"Prefeitura de Mara\u00fa continua com equipes removendo pelotas de \u00f3leo nas praias com apoio das comunidades","slug":"prefeitura-de-marau-continua-com-equipes-removendo-pelotas-de-oleo-nas-praias-com-apoio-das-comunidades","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags\/1751"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts?tags=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}