{"id":140024,"date":"2025-06-02T15:48:32","date_gmt":"2025-06-02T18:48:32","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=140024"},"modified":"2025-06-02T15:48:32","modified_gmt":"2025-06-02T18:48:32","slug":"corpo-em-estado-de-decomposicao-e-encontrado-na-praia-de-aibim-na-peninsula-de-marau","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2025\/06\/02\/corpo-em-estado-de-decomposicao-e-encontrado-na-praia-de-aibim-na-peninsula-de-marau\/","title":{"rendered":"CORPO EM ESTADO DE DECOMPOSI\u00c7\u00c3O \u00c9 ENCONTRADO NA PRAIA DE AIBIM, NA PEN\u00cdNSULA DE MARA\u00da"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\"><span class=\"s2\">Um corpo em avan\u00e7ado estado de decomposi\u00e7\u00e3o foi encontrado na manh\u00e3 desta segunda-feira (02), na Praia de Aibim, localizada nas proximidades de Piracanga, na Pen\u00ednsula de Mara\u00fa, no sul da Bahia.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span class=\"s2\">Segundo informa\u00e7\u00f5es, o cad\u00e1ver foi avistado por um pescador da regi\u00e3o, que imediatamente acionou a Pol\u00edcia Militar. O corpo estava na faixa de areia e, de acordo com as primeiras an\u00e1lises, possivelmente foi trazido pelo mar.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span class=\"s2\">A Pol\u00edcia T\u00e9cnica foi chamada para realizar a remo\u00e7\u00e3o e iniciar os procedimentos de per\u00edcia. At\u00e9 o momento, a v\u00edtima ainda n\u00e3o foi identificada.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span class=\"s2\">O caso ser\u00e1 investigado pela Pol\u00edcia Civil, que deve apurar as circunst\u00e2ncias da morte e tentar identificar o homem. Mais informa\u00e7\u00f5es ser\u00e3o divulgadas \u00e0 medida que as investiga\u00e7\u00f5es avan\u00e7arem.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um corpo em avan\u00e7ado estado de decomposi\u00e7\u00e3o foi encontrado na manh\u00e3 desta segunda-feira (02), na Praia de Aibim, localizada nas proximidades de Piracanga, na Pen\u00ednsula de Mara\u00fa, no sul da Bahia. Segundo informa\u00e7\u00f5es, o cad\u00e1ver foi avistado por um pescador da regi\u00e3o, que imediatamente acionou a Pol\u00edcia Militar. O corpo estava na faixa de areia e, de acordo com as primeiras an\u00e1lises, possivelmente foi trazido pelo mar. A Pol\u00edcia T\u00e9cnica foi chamada para realizar a remo\u00e7\u00e3o e iniciar os procedimentos de per\u00edcia. At\u00e9 o momento, a v\u00edtima ainda n\u00e3o foi identificada. O caso ser\u00e1 investigado pela Pol\u00edcia Civil, que deve [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":140027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/140024"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=140024"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/140024\/revisions"}],"predecessor-version":[{"id":140028,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/140024\/revisions\/140028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/140027"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=140024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=140024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=140024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}