{"id":137974,"date":"2024-08-30T12:51:00","date_gmt":"2024-08-30T15:51:00","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=137974"},"modified":"2024-08-30T12:51:00","modified_gmt":"2024-08-30T15:51:00","slug":"ubaitaba-gracinha-viana-tem-candidatura-para-prefeita-pela-justica-eleitoral","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2024\/08\/30\/ubaitaba-gracinha-viana-tem-candidatura-para-prefeita-pela-justica-eleitoral\/","title":{"rendered":"UBAITABA: GRACINHA VIANA TEM CANDIDATURA PARA PREFEITA PELA JUSTI\u00c7A ELEITORAL"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A Justi\u00e7a Eleitoral deferiu o pedido de registro de candidatura de Gracinha Viana para o cargo de prefeita de Ubaitaba. A decis\u00e3o foi publicada nesta quinta-feira (29), confirmando que Gracinha est\u00e1 apta a disputar as elei\u00e7\u00f5es municipais deste ano. Gracinha Viana traz sua experi\u00eancia e compromisso para a disputa em Ubaitaba, com uma campanha pautada pela transpar\u00eancia, honestidade e desejo de mudan\u00e7a.<\/p>\n<p style=\"text-align: justify;\">A decis\u00e3o de deferimento consolida sua posi\u00e7\u00e3o na corrida eleitoral e refor\u00e7a a confian\u00e7a de seus apoiadores na legalidade e legitimidade de sua candidatura. Com o registro deferido, Gracinha Viana, seu vice Beto da Padaria e sua equipe seguem firmes na campanha, levando suas propostas e planos de governo para a popula\u00e7\u00e3o de Ubaitaba, com o objetivo de transformar e desenvolver o munic\u00edpio.\u00a0<em>(Reda\u00e7\u00e3o: Ascom\/Gracinha Viana)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a Eleitoral deferiu o pedido de registro de candidatura de Gracinha Viana para o cargo de prefeita de Ubaitaba. A decis\u00e3o foi publicada nesta quinta-feira (29), confirmando que Gracinha est\u00e1 apta a disputar as elei\u00e7\u00f5es municipais deste ano. Gracinha Viana traz sua experi\u00eancia e compromisso para a disputa em Ubaitaba, com uma campanha pautada pela transpar\u00eancia, honestidade e desejo de mudan\u00e7a. A decis\u00e3o de deferimento consolida sua posi\u00e7\u00e3o na corrida eleitoral e refor\u00e7a a confian\u00e7a de seus apoiadores na legalidade e legitimidade de sua candidatura. Com o registro deferido, Gracinha Viana, seu vice Beto da Padaria e sua equipe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":137975,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/137974"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=137974"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/137974\/revisions"}],"predecessor-version":[{"id":137976,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/137974\/revisions\/137976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/137975"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=137974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=137974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=137974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}