{"id":136141,"date":"2023-08-28T22:15:46","date_gmt":"2023-08-29T01:15:46","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=136141"},"modified":"2023-08-28T22:15:46","modified_gmt":"2023-08-29T01:15:46","slug":"cbs-entrega-ao-prefeito-manasses-obra-de-pavimentacao-em-tsd-em-tremembe-e-santa-maria","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2023\/08\/28\/cbs-entrega-ao-prefeito-manasses-obra-de-pavimentacao-em-tsd-em-tremembe-e-santa-maria\/","title":{"rendered":"CBS ENTREGA AO PREFEITO MANASS\u00c9S OBRA DE PAVIMENTA\u00c7\u00c3O EM TSD EM TREMEMB\u00c9 E SANTA MARIA\u00a0"},"content":{"rendered":"<div><\/div>\n<p>&nbsp;<\/p>\n<p>O prefeito de Mara\u00fa, esteve na tarde desta sexta-feira, 25\/08, em Trememb\u00e9 e na Santa Maria, para receber da empresa CBS, a conclus\u00e3o das obras de pavimenta\u00e7\u00e3o do tipo TSD (tratamento superficial duplo) das localidades.<\/p>\n<p><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935.jpeg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\"size-full wp-image-136151 aligncenter\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935.jpeg\"  alt=\"\" width=\"730\" height=\"548\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935.jpeg 730w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935-180x135.jpeg 180w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935-400x300.jpeg 400w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0935-600x450.jpeg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<p>O prefeito estava acompanhado do vereador e presidente da C\u00e2mara, Osvaldo Ferreira Mota, do Secret\u00e1rio de Infraestrutura, Adson e da primeira-dama Rose e o suplente de vereador Jaime Mota. Na oportunidade, o gestor percorreu todo trajeto das ruas contempladas para \u00faltima vistoria.<\/p>\n<p><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0893_jpg.jpeg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\"size-full wp-image-136150 aligncenter\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0893_jpg.jpeg\"  alt=\"\" width=\"730\" height=\"973\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0893_jpg.jpeg 730w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0893_jpg-225x300.jpeg 225w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<p>De acordo com Manass\u00e9s, a obra deve ser inaugurada nas pr\u00f3ximas semanas com a presen\u00e7a do Deputado Federal Neto Carletto e do Ex-deputado federal e presidente do Avante, Ronaldo Carletto que foi o autor da emenda parlamentar para a realiza\u00e7\u00e3o da obra.<\/p>\n<p><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0996_jpg-730x430-1.jpeg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\"size-full wp-image-136149 aligncenter\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0996_jpg-730x430-1.jpeg\"  alt=\"\" width=\"730\" height=\"430\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0996_jpg-730x430-1.jpeg 730w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2023\/08\/IMG_0996_jpg-730x430-1-300x177.jpeg 300w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O prefeito de Mara\u00fa, esteve na tarde desta sexta-feira, 25\/08, em Trememb\u00e9 e na Santa Maria, para receber da empresa CBS, a conclus\u00e3o das obras de pavimenta\u00e7\u00e3o do tipo TSD (tratamento superficial duplo) das localidades. O prefeito estava acompanhado do vereador e presidente da C\u00e2mara, Osvaldo Ferreira Mota, do Secret\u00e1rio de Infraestrutura, Adson e da primeira-dama Rose e o suplente de vereador Jaime Mota. Na oportunidade, o gestor percorreu todo trajeto das ruas contempladas para \u00faltima vistoria. De acordo com Manass\u00e9s, a obra deve ser inaugurada nas pr\u00f3ximas semanas com a presen\u00e7a do Deputado Federal Neto Carletto e do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":136152,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/136141"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=136141"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/136141\/revisions"}],"predecessor-version":[{"id":136153,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/136141\/revisions\/136153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/136152"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=136141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=136141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=136141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}