{"id":136125,"date":"2023-08-25T00:30:57","date_gmt":"2023-08-25T03:30:57","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=136125"},"modified":"2023-08-25T00:30:57","modified_gmt":"2023-08-25T03:30:57","slug":"marau-bebe-de-seis-meses-morre-asfixiado-em-lencol","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2023\/08\/25\/marau-bebe-de-seis-meses-morre-asfixiado-em-lencol\/","title":{"rendered":"MARA\u00da: BEB\u00ca DE SEIS MESES MORRE ASFIXIADO EM LEN\u00c7OL"},"content":{"rendered":"<p>Um beb\u00ea de seis meses morreu asfixiado na quarta-feira (23), no povoado de Algod\u00f5es, em Mara\u00fa, no baixo sul da Bahia.<\/p>\n<p>O beb\u00ea teria morrido ap\u00f3s se enrolar em um len\u00e7ol, de acordo com a TV Bahia. Andr\u00e9ia Oliveira, titular da delegacia de Mara\u00fa, afirmou que a m\u00e3e do beb\u00ea disse, em depoimento, que n\u00e3o estava em casa quando a situa\u00e7\u00e3o aconteceu e que a crian\u00e7a estaria com uma prima.<\/p>\n<p>Segundo a Pol\u00edcia Civil, o laudo do Departamento de Pol\u00edcia T\u00e9cnica (DPT) de Ilh\u00e9us passar\u00e1 por necr\u00f3psia, e o laudo deve esclarecer a causa da morte. A Delegacia Territorial (DT) de Mara\u00fa foi acionada para a expedi\u00e7\u00e3o de guias periciais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um beb\u00ea de seis meses morreu asfixiado na quarta-feira (23), no povoado de Algod\u00f5es, em Mara\u00fa, no baixo sul da Bahia. O beb\u00ea teria morrido ap\u00f3s se enrolar em um len\u00e7ol, de acordo com a TV Bahia. Andr\u00e9ia Oliveira, titular da delegacia de Mara\u00fa, afirmou que a m\u00e3e do beb\u00ea disse, em depoimento, que n\u00e3o estava em casa quando a situa\u00e7\u00e3o aconteceu e que a crian\u00e7a estaria com uma prima. Segundo a Pol\u00edcia Civil, o laudo do Departamento de Pol\u00edcia T\u00e9cnica (DPT) de Ilh\u00e9us passar\u00e1 por necr\u00f3psia, e o laudo deve esclarecer a causa da morte. A Delegacia Territorial (DT) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":129819,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/136125"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=136125"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/136125\/revisions"}],"predecessor-version":[{"id":136126,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/136125\/revisions\/136126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/129819"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=136125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=136125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=136125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}