{"id":132825,"date":"2022-06-18T03:28:13","date_gmt":"2022-06-18T06:28:13","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=132825"},"modified":"2022-06-18T03:28:13","modified_gmt":"2022-06-18T06:28:13","slug":"batista-lima-jaldo-rodrigues-e-pablo-no-sao-joao-de-camamu","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2022\/06\/18\/batista-lima-jaldo-rodrigues-e-pablo-no-sao-joao-de-camamu\/","title":{"rendered":"BATISTA LIMA, JALDO RODRIGUES E PABLO NO S\u00c3O JO\u00c3O DE CAMAMU"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">A prefeitura de Camamu divulgou a programa\u00e7\u00e3o musical completa do S\u00e3o Jo\u00e3o 2022. Ser\u00e3o sete dias de festa, de 21 a 27 de junho que \u00e9 anivers\u00e1rio da cidade. As principais atra\u00e7\u00f5es do evento s\u00e3o Jaldo Rodrigues, ex-vocalista da Banda Sem Retoque, Batista Lima (ex-vocalista da Lim\u00e3o Com Mel), Arriba Saia e Pablo.<\/p>\n<p style=\"text-align: justify;\">O S\u00e3o Jo\u00e3o de Camamu \u00e9 um dos mais tradicionais da regi\u00e3o e durante o per\u00edodo junino a cidade \u00e9 toda preparada para receber visitantes e para um grande movimento no com\u00e9rcio.<\/p>\n<p><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14.jpeg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\" wp-image-132826 aligncenter\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14-821x1024.jpeg\"  alt=\"\" width=\"593\" height=\"740\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14-821x1024.jpeg 821w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14-241x300.jpeg 241w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14-768x958.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14-1232x1536.jpeg 1232w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-18-at-03.26.14.jpeg 1242w\" sizes=\"(max-width: 593px) 100vw, 593px\" \/><\/a><\/p>\n<div class=\"row\">\n<div class=\"col-md-2 margin-b-30 col-xs-3\">\n<article>\n<div class=\"article-inner\"><\/div>\n<\/article>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A prefeitura de Camamu divulgou a programa\u00e7\u00e3o musical completa do S\u00e3o Jo\u00e3o 2022. Ser\u00e3o sete dias de festa, de 21 a 27 de junho que \u00e9 anivers\u00e1rio da cidade. As principais atra\u00e7\u00f5es do evento s\u00e3o Jaldo Rodrigues, ex-vocalista da Banda Sem Retoque, Batista Lima (ex-vocalista da Lim\u00e3o Com Mel), Arriba Saia e Pablo. O S\u00e3o Jo\u00e3o de Camamu \u00e9 um dos mais tradicionais da regi\u00e3o e durante o per\u00edodo junino a cidade \u00e9 toda preparada para receber visitantes e para um grande movimento no com\u00e9rcio.<\/p>\n","protected":false},"author":2,"featured_media":132827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/132825"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=132825"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/132825\/revisions"}],"predecessor-version":[{"id":132829,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/132825\/revisions\/132829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/132827"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=132825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=132825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=132825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}