{"id":132704,"date":"2022-06-03T12:57:43","date_gmt":"2022-06-03T15:57:43","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=132704"},"modified":"2022-06-03T13:06:12","modified_gmt":"2022-06-03T16:06:12","slug":"acao-conjunta-da-pm-policia-civil-e-cipe-cacaueira-recupera-produtos-furtados-em-barra-grande","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2022\/06\/03\/acao-conjunta-da-pm-policia-civil-e-cipe-cacaueira-recupera-produtos-furtados-em-barra-grande\/","title":{"rendered":"A\u00c7\u00c3O CONJUNTA DA PM,  POL\u00cdCIA CIVIL E CIPE CACAUEIRA RECUPERA PRODUTOS FURTADOS EM BARRA GRANDE"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>No \u00faltimo dia 29, uma grande a\u00e7\u00e3o conjunta entre as pol\u00edcias civil e militar de Barra Grande e da Cipe Cacaueira, resultou a recupera\u00e7\u00e3o de v\u00e1rios objetos, m\u00f3veis e eletrodom\u00e9sticos furtados de uma resid\u00eancia. Um dos autores foi detido no Mangue Verde e conduzido a delegacia de Pol\u00edcia. O material foi recuperado em v\u00e1rios locais que foram indicados pelo pr\u00f3prio autor do delito.<\/p>\n<p><strong>MATERIAL RECUPERADO<\/strong><\/p>\n<p>01 geladeira<br \/>\n01 frigobar<br \/>\n01 Tv LG;<br \/>\n01 colch\u00e3o de casal;<br \/>\n01 colch\u00e3o solteiro;<br \/>\n01 espelho de parede;<br \/>\n01 bike marca Gonew;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; No \u00faltimo dia 29, uma grande a\u00e7\u00e3o conjunta entre as pol\u00edcias civil e militar de Barra Grande e da Cipe Cacaueira, resultou a recupera\u00e7\u00e3o de v\u00e1rios objetos, m\u00f3veis e eletrodom\u00e9sticos furtados de uma resid\u00eancia. Um dos autores foi detido no Mangue Verde e conduzido a delegacia de Pol\u00edcia. O material foi recuperado em v\u00e1rios locais que foram indicados pelo pr\u00f3prio autor do delito. MATERIAL RECUPERADO 01 geladeira 01 frigobar 01 Tv LG; 01 colch\u00e3o de casal; 01 colch\u00e3o solteiro; 01 espelho de parede; 01 bike marca Gonew;<\/p>\n","protected":false},"author":2,"featured_media":132705,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/132704"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=132704"}],"version-history":[{"count":3,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/132704\/revisions"}],"predecessor-version":[{"id":132708,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/132704\/revisions\/132708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/132705"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=132704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=132704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=132704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}