{"id":131152,"date":"2021-12-03T12:20:44","date_gmt":"2021-12-03T15:20:44","guid":{"rendered":"https:\/\/www.barragrande24horas.com.br\/v1\/?p=131152"},"modified":"2021-12-05T14:36:58","modified_gmt":"2021-12-05T17:36:58","slug":"homem-com-mandado-de-prisao-por-homicidio-em-camamu-e-preso-pela-policia-civil-de-barra-grande","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2021\/12\/03\/homem-com-mandado-de-prisao-por-homicidio-em-camamu-e-preso-pela-policia-civil-de-barra-grande\/","title":{"rendered":"HOMEM COM MANDADO DE PRIS\u00c3O POR HOMIC\u00cdDIO EM CAMAMU \u00c9 PRESO PELA POL\u00cdCIA CIVIL DE BARRA GRANDE"},"content":{"rendered":"<h1 class=\"content-head__title\"><\/h1>\n<div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"34\" data-block-id=\"2\">\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2021\/12\/foto-5-1024x576.jpg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\" wp-image-131153 aligncenter\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2021\/12\/foto-5-1024x576-1024x576.jpg\"  alt=\"\" width=\"585\" height=\"329\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2021\/12\/foto-5-1024x576.jpg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2021\/12\/foto-5-1024x576-533x300.jpg 533w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2021\/12\/foto-5-1024x576-768x432.jpg 768w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/a><\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Um homem com mandado de pris\u00e3o em aberto pelo crime de homic\u00eddio na cidade de Camamu, foi preso pela Pol\u00edcia Civil de Mara\u00fa. A pris\u00e3o foi feita por policiais civis em Barra Grande na tarde da \u00faltima quinta-feira, 02\/12.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">O acusado foi conduzido para delegacia de Barra Grande, suspeito de cometer um furto e posteriormente, foi constatado que o mesmo tinha um mandado de pris\u00e3o em aberto por homic\u00eddio que vitimou Edvaldo Oliveira Santos com golpes de porrete e faca, no local conhecido como Invas\u00e3o da Pinheira, em Camamu, no dia 19\/11\/2021.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Ap\u00f3s cometer o crime, o acusado fugiu para o distrito de Barra Grande. O suspeito confessou o homic\u00eddio e disse que o crime foi por causado por ci\u00fames entre a companheira e a v\u00edtima. O preso foi entregue a Pol\u00edcia Civil de Camamu para as medidas cab\u00edveis.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"40\" data-block-id=\"3\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um homem com mandado de pris\u00e3o em aberto pelo crime de homic\u00eddio na cidade de Camamu, foi preso pela Pol\u00edcia Civil de Mara\u00fa. A pris\u00e3o foi feita por policiais civis em Barra Grande na tarde da \u00faltima quinta-feira, 02\/12. O acusado foi conduzido para delegacia de Barra Grande, suspeito de cometer um furto e posteriormente, foi constatado que o mesmo tinha um mandado de pris\u00e3o em aberto por homic\u00eddio que vitimou Edvaldo Oliveira Santos com golpes de porrete e faca, no local conhecido como Invas\u00e3o da Pinheira, em Camamu, no dia 19\/11\/2021. Ap\u00f3s cometer o crime, o acusado fugiu para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131153,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/131152"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=131152"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/131152\/revisions"}],"predecessor-version":[{"id":131154,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/131152\/revisions\/131154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/131153"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=131152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=131152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=131152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}