{"id":128896,"date":"2021-06-13T22:40:49","date_gmt":"2021-06-14T01:40:49","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=128896"},"modified":"2021-06-13T22:40:49","modified_gmt":"2021-06-14T01:40:49","slug":"pm-de-marau-e-peto-encerram-festa-clandestina-com-mais-de-100-pessoas-em-bar-da-zona-rural","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2021\/06\/13\/pm-de-marau-e-peto-encerram-festa-clandestina-com-mais-de-100-pessoas-em-bar-da-zona-rural\/","title":{"rendered":"PM DE MARA\u00da E PETO ENCERRAM FESTA CLANDESTINA COM MAIS DE 100 PESSOAS EM BAR DA ZONA RURAL"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"PM ENCERRA FESTA CLANDESTINA NA ZONA RURAL DE MARA\u00da\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/2Cy3TnO5LoY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Em meio \u00e0 explos\u00e3o de casos e mortes causadas em decorr\u00eancia da covid-19, a Pol\u00edcia Militar de Mara\u00fa, em a\u00e7\u00e3o conjunta com a PETO &#8211; Pelot\u00e3o de Emprego T\u00e1tico Operacional da da 72\u00aa CIPM\/ Itacar\u00e9, encerrou uma festa clandestina na noite do \u00faltimo s\u00e1bado (12\/06), zona Rural de Mara\u00fa.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"PM MARA\u00da\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/pgVDgE2Bt2o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>O evento ocorreu em um bar localizado entre o Ponto do Caf\u00e9 e o S\u00e3o Raimundo, \u00e0s margens da rodovia BR030, que liga Mara\u00fa a Ubaitaba.<br \/>\nPoliciais militares chegarem ao bar por volta da 00:00, constataram a presen\u00e7a de cerca de 150 pessoas sem m\u00e1scara. O grupo foi dispersado e n\u00e3o houve deten\u00e7\u00f5es.<\/p>\n<p><iframe loading=\"lazy\" title=\"PM CHEGA E ENCERRA FESTA NA ZONA RURAL DE MARA\u00da\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/RU15YhnpGW4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio \u00e0 explos\u00e3o de casos e mortes causadas em decorr\u00eancia da covid-19, a Pol\u00edcia Militar de Mara\u00fa, em a\u00e7\u00e3o conjunta com a PETO &#8211; Pelot\u00e3o de Emprego T\u00e1tico Operacional da da 72\u00aa CIPM\/ Itacar\u00e9, encerrou uma festa clandestina na noite do \u00faltimo s\u00e1bado (12\/06), zona Rural de Mara\u00fa. &nbsp; O evento ocorreu em um bar localizado entre o Ponto do Caf\u00e9 e o S\u00e3o Raimundo, \u00e0s margens da rodovia BR030, que liga Mara\u00fa a Ubaitaba. Policiais militares chegarem ao bar por volta da 00:00, constataram a presen\u00e7a de cerca de 150 pessoas sem m\u00e1scara. O grupo foi dispersado e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":128899,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,27,3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/128896"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=128896"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/128896\/revisions"}],"predecessor-version":[{"id":128898,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/128896\/revisions\/128898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/128899"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=128896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=128896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=128896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}