{"id":126299,"date":"2020-11-13T21:04:17","date_gmt":"2020-11-14T00:04:17","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=126299"},"modified":"2020-11-13T21:04:17","modified_gmt":"2020-11-14T00:04:17","slug":"marau-tem-16-casos-ativos-da-covid-19","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2020\/11\/13\/marau-tem-16-casos-ativos-da-covid-19\/","title":{"rendered":"MARA\u00da TEM 16 CASOS ATIVOS DA COVID-19\u00a0"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-126303  aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.48.34.jpeg\" alt=\"\" width=\"585\" height=\"585\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.48.34.jpeg 1000w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.48.34-300x300.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.48.34-768x768.jpeg 768w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/p>\n<div class=\"elementor-element elementor-element-3f8c368 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3f8c368\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n<div class=\"elementor-widget-container\">\n<p>Mara\u00fa tem apenas 16 casos ativos da COVID-19 e 398 curados de acordo com o boletim da Secretaria de Sa\u00fade desta sexta-feira, 13. Foram confirmados mais 6 casos ativos: 01 na Sede e 05 em Barra Grande, al\u00e9m de 01 novo pacientes curado em Piabanha.<\/p>\n<p>A Vigil\u00e2ncia Epidemiol\u00f3gica registrou 05 novos casos suspeitos: 01 em Taipu de Dentro, 01 em Saqua\u00edra, 01 na Santa Maria e 02 em Barra Grande. 01 caso suspeito na Sede e 01 em Piabanha foram descartados. Mara\u00fa tem 1 \u00f3bito por outras causas, j\u00e1 que um paciente infectado com a COVID-19, morreu em decorr\u00eancia de outra patologia.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-126302  aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.49.44.jpeg\" alt=\"\" width=\"583\" height=\"583\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.49.44.jpeg 1080w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.49.44-300x300.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.49.44-768x768.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-19.49.44-1024x1024.jpeg 1024w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/><\/p>\n<p>At\u00e9 a presente data, Mara\u00fa contabiliza, 421 casos confirmados, 398 pacientes recuperados, 16 ativos, 6 \u00f3bitos, 09 suspeitos, 09 aguardando resultado e 480 casos negativos. Disk Covid (73) 9 9965-9338 \u2013 (73) 9 9836-5649.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-126301  aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-20.04.14.jpeg\" alt=\"\" width=\"583\" height=\"583\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-20.04.14.jpeg 1000w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-20.04.14-300x300.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-13-at-20.04.14-768x768.jpeg 768w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/><\/p>\n<p>A Secretaria Municipal de Sa\u00fade orienta a popula\u00e7\u00e3o a refor\u00e7ar as medidas sanit\u00e1rias definidas para evitar a dissemina\u00e7\u00e3o da COVID-19, utilizando m\u00e1scaras caseiras, realizando a higieniza\u00e7\u00e3o adequada das m\u00e3os, evitando contato f\u00edsico (mantendo a dist\u00e2ncia m\u00ednima de 2 metros entre as pessoas) e se mantendo em domic\u00edlio sempre que poss\u00edvel.<\/p>\n<p>ASCOM \u2013 Prefeitura de Mara\u00fa<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Mara\u00fa tem apenas 16 casos ativos da COVID-19 e 398 curados de acordo com o boletim da Secretaria de Sa\u00fade desta sexta-feira, 13. Foram confirmados mais 6 casos ativos: 01 na Sede e 05 em Barra Grande, al\u00e9m de 01 novo pacientes curado em Piabanha. A Vigil\u00e2ncia Epidemiol\u00f3gica registrou 05 novos casos suspeitos: 01 em Taipu de Dentro, 01 em Saqua\u00edra, 01 na Santa Maria e 02 em Barra Grande. 01 caso suspeito na Sede e 01 em Piabanha foram descartados. Mara\u00fa tem 1 \u00f3bito por outras causas, j\u00e1 que um paciente infectado com a COVID-19, morreu em decorr\u00eancia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126303,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[3450],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/126299"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=126299"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/126299\/revisions"}],"predecessor-version":[{"id":126304,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/126299\/revisions\/126304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/126303"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=126299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=126299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=126299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}