{"id":125792,"date":"2020-09-17T20:19:57","date_gmt":"2020-09-17T23:19:57","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=125792"},"modified":"2020-09-17T20:34:42","modified_gmt":"2020-09-17T23:34:42","slug":"chega-a-fase-final-a-construc%cc%a7a%cc%83o-da-academia-da-saude-em-marau","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2020\/09\/17\/chega-a-fase-final-a-construc%cc%a7a%cc%83o-da-academia-da-saude-em-marau\/","title":{"rendered":"Chega \u00e0 fase final a construc\u0327a\u0303o da Academia da Sau\u0301de em Mara\u00fa"},"content":{"rendered":"<div id=\"attachment_125793\" style=\"width: 581px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-17-at-20.01.48-1.jpeg\" class=\"gallery_colorbox\" rel=\"attachment wp-att-125793\"><img aria-describedby=\"caption-attachment-125793\" loading=\"lazy\" class=\" wp-image-125793\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-17-at-20.01.48-1.jpeg\"  alt=\"\" width=\"571\" height=\"428\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-17-at-20.01.48-1.jpeg 600w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-17-at-20.01.48-1-400x300.jpeg 400w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/><\/a><p id=\"caption-attachment-125793\" class=\"wp-caption-text\">Constru\u00e7\u00e3o da Academia de Sa\u00fade em Mara\u00fa.<\/p><\/div>\n<p>A prefeitura de Mara\u00fa est\u00e1 concluindo as obras da Academia de Sa\u00fade na Sede.\u00a0A a\u00e7\u00e3o tem como objetivo contribuir para a promo\u00e7\u00e3o da sa\u00fade da popula\u00e7\u00e3o a partir da implanta\u00e7\u00e3o de espa\u00e7os com infraestrutura adequada, equipamentos e profissionais qualificados para a orienta\u00e7\u00e3o de atividade f\u00edsica e de lazer, que permitam uma vida saud\u00e1vel. O investimento \u00e9 de pouco mais de R$ 210 mil reais. O recurso \u00e9 proveniente da cess\u00e3o onerosa \u2013 volumes excedentes do pr\u00e9-sal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prefeitura de Mara\u00fa est\u00e1 concluindo as obras da Academia de Sa\u00fade na Sede.\u00a0A a\u00e7\u00e3o tem como objetivo contribuir para a promo\u00e7\u00e3o da sa\u00fade da popula\u00e7\u00e3o a partir da implanta\u00e7\u00e3o de espa\u00e7os com infraestrutura adequada, equipamentos e profissionais qualificados para a orienta\u00e7\u00e3o de atividade f\u00edsica e de lazer, que permitam uma vida saud\u00e1vel. O investimento \u00e9 de pouco mais de R$ 210 mil reais. O recurso \u00e9 proveniente da cess\u00e3o onerosa \u2013 volumes excedentes do pr\u00e9-sal.<\/p>\n","protected":false},"author":2,"featured_media":125793,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[3329],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/125792"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=125792"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/125792\/revisions"}],"predecessor-version":[{"id":125795,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/125792\/revisions\/125795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/125793"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=125792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=125792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=125792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}