{"id":124566,"date":"2020-07-05T19:15:38","date_gmt":"2020-07-05T22:15:38","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=124566"},"modified":"2020-07-05T19:15:39","modified_gmt":"2020-07-05T22:15:39","slug":"camamu-chega-a-214-casos-de-coronavirus-e-mais-2-pessoas-morreram","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2020\/07\/05\/camamu-chega-a-214-casos-de-coronavirus-e-mais-2-pessoas-morreram\/","title":{"rendered":"Camamu chega a 214 casos de Coronav\u00edrus e mais 2 pessoas morreram"},"content":{"rendered":"<p><a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/07\/106986610_653555642168886_1930772050023983269_o-768x768.jpg\" class=\"gallery_colorbox\" rel=\"attachment wp-att-124567\"><img loading=\"lazy\" class=\" wp-image-124567 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/07\/106986610_653555642168886_1930772050023983269_o-768x768.jpg\"  alt=\"\" width=\"566\" height=\"566\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/07\/106986610_653555642168886_1930772050023983269_o-768x768.jpg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/07\/106986610_653555642168886_1930772050023983269_o-768x768-300x300.jpg 300w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/><\/a><\/p>\n<p>Do <a href=\"https:\/\/portalbaixosul.com.br\/camamu-chega-a-214-casos-de-coronavirus-e-mais-2-pessoas-morreram\/\">Portal Baixo Sul<\/a><\/p>\n<p>Camamu, no Baixo Sul, registrou neste domingo (5), 214 casos positivos de Coronav\u00edrus e a morte de mais 2 pacientes que tiveram exames testados positivos para Covid-19. Segundo boletim da Secretaria da Sa\u00fade, o primeiro \u00f3bito trata-se de um homem, de 85 anos, que deu entrada no Hospital Municipal de Camamu, j\u00e1 sem os sinais vitais.\u00a0O segundo \u00f3bito trata-se de uma mulher de 59 anos, que havia sido internada em outro munic\u00edpio por outras causas, e acabou contraindo o Coronav\u00edrus, vindo a \u00f3bito. \u201cO munic\u00edpio s\u00f3 foi informado hoje\u201d, disse a nota. Veja boletim.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Portal Baixo Sul Camamu, no Baixo Sul, registrou neste domingo (5), 214 casos positivos de Coronav\u00edrus e a morte de mais 2 pacientes que tiveram exames testados positivos para Covid-19. Segundo boletim da Secretaria da Sa\u00fade, o primeiro \u00f3bito trata-se de um homem, de 85 anos, que deu entrada no Hospital Municipal de Camamu, j\u00e1 sem os sinais vitais.\u00a0O segundo \u00f3bito trata-se de uma mulher de 59 anos, que havia sido internada em outro munic\u00edpio por outras causas, e acabou contraindo o Coronav\u00edrus, vindo a \u00f3bito. \u201cO munic\u00edpio s\u00f3 foi informado hoje\u201d, disse a nota. Veja boletim.<\/p>\n","protected":false},"author":2,"featured_media":124567,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17],"tags":[41,3039],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/124566"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=124566"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/124566\/revisions"}],"predecessor-version":[{"id":124569,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/124566\/revisions\/124569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/124567"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=124566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=124566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=124566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}