{"id":121079,"date":"2020-02-19T06:15:30","date_gmt":"2020-02-19T09:15:30","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=121079"},"modified":"2020-02-19T06:15:30","modified_gmt":"2020-02-19T09:15:30","slug":"ao-lado-do-governador-rui-costa-prefeita-gracinha-recebe-novo-onibus-escolar-de-emenda-do-deputado-federal-ronaldo-carletto","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2020\/02\/19\/ao-lado-do-governador-rui-costa-prefeita-gracinha-recebe-novo-onibus-escolar-de-emenda-do-deputado-federal-ronaldo-carletto\/","title":{"rendered":"Ao lado do governador Rui Costa, prefeita Gracinha recebe novo \u00f4nibus escolar de emenda do deputado federal Ronaldo Carletto"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-121080 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2020-02-19-at-06.14.11.jpeg\" alt=\"\" width=\"584\" height=\"477\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2020-02-19-at-06.14.11.jpeg 898w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2020-02-19-at-06.14.11-300x245.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2020-02-19-at-06.14.11-768x628.jpeg 768w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/p>\n<p class=\"photoswipe-wrapper\">Em mais uma a\u00e7\u00e3o destinada a valorizar e dinamizar a educa\u00e7\u00e3o municipal, a prefeita de Mara\u00fa, Gracinha Viana ao lado do governador Rui Costa, esteve presente no estacionamento da Governadoria, no Centro Administrativo da Bahia (CAB), em Salvador,&nbsp;para receber oficialmente, um novo \u00f4nibus escolar para a Secretaria Municipal de Educa\u00e7\u00e3o, por meio da emenda parlamentar do deputado federal Ronaldo Carletto.&nbsp;<\/p>\n<p>O \u00f4nibu \u00e9 do modelo ORE 1 (\u00d4nibus Rural Escolar), com capacidade para 29 lugares, e possue Dispositivo de Poltrona M\u00f3vel (DPM) para embarque e desembarque de estudante com defici\u00eancia ou com mobilidade reduzida. O ve\u00edculo&nbsp;ir\u00e1 atender aos estudantes das redea municipal de ensino.<\/p>\n<p>Na oportunidade, a prefeita agradeceu o empenho e o comprometimento do deputado federal Ronaldo Carletto, enalteceu os investimentos da Prefeitura com a educa\u00e7\u00e3o do munic\u00edpio e afirmou que vai continuar buscando mais recursos para o munic\u00edpio junto ao Governo do Estado.<\/p>\n<p style=\"text-align: center;\"><strong>ASCOM &#8211; Prefeitura de Mara\u00fa<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em mais uma a\u00e7\u00e3o destinada a valorizar e dinamizar a educa\u00e7\u00e3o municipal, a prefeita de Mara\u00fa, Gracinha Viana ao lado do governador Rui Costa, esteve presente no estacionamento da Governadoria, no Centro Administrativo da Bahia (CAB), em Salvador,&nbsp;para receber oficialmente, um novo \u00f4nibus escolar para a Secretaria Municipal de Educa\u00e7\u00e3o, por meio da emenda parlamentar do deputado federal Ronaldo Carletto.&nbsp; O \u00f4nibu \u00e9 do modelo ORE 1 (\u00d4nibus Rural Escolar), com capacidade para 29 lugares, e possue Dispositivo de Poltrona M\u00f3vel (DPM) para embarque e desembarque de estudante com defici\u00eancia ou com mobilidade reduzida. O ve\u00edculo&nbsp;ir\u00e1 atender aos estudantes das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":121080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17,19,21,27],"tags":[2116,2117],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/121079"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=121079"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/121079\/revisions"}],"predecessor-version":[{"id":121081,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/121079\/revisions\/121081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/121080"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=121079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=121079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=121079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}