{"id":120524,"date":"2019-12-27T20:28:34","date_gmt":"2019-12-27T23:28:34","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=120524"},"modified":"2019-12-27T20:28:34","modified_gmt":"2019-12-27T23:28:34","slug":"neymar-gabriel-medina-e-lucas-lima-ja-estao-em-barra-grande-para-curtir-virada-de-ano-no-reveillon-mil-sorrisos-2","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/12\/27\/neymar-gabriel-medina-e-lucas-lima-ja-estao-em-barra-grande-para-curtir-virada-de-ano-no-reveillon-mil-sorrisos-2\/","title":{"rendered":"Neymar, Gabriel Medina e Lucas Lima j\u00e1 est\u00e3o em Barra Grande para curtir virada de ano no r\u00e9veillon Mil Sorrisos"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-120521 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/12\/2412242-neymar-canta-e-danca-em-show-de-thiaguin-950x0-3-768x512-768x445.jpg\" alt=\"\" width=\"585\" height=\"340\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/12\/2412242-neymar-canta-e-danca-em-show-de-thiaguin-950x0-3-768x512-768x445.jpg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/12\/2412242-neymar-canta-e-danca-em-show-de-thiaguin-950x0-3-768x512-768x445-300x174.jpg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/p>\n<p>Parece que Neymar Jr. j\u00e1 tem uma tradi\u00e7\u00e3o para o R\u00e9veillon: pelo terceiro ano consecutivo, o jogador deve passar a virada de ano em Barra Grande, na Pen\u00ednsula de Mara\u00fa.&nbsp;O atacante do Paris Saint Germain (PSG) j\u00e1 chegou a Taipu de Fora e est\u00e1 mais uma vez hospedado na mans\u00e3o do publicit\u00e1rio Duda Mendon\u00e7a.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>E, para receber o novo ano como se deve, claro, o craque do PSG, j\u00e1 garantiu a presen\u00e7a dos insepar\u00e1veis par\u00e7as. Entre eles ningu\u00e9m mais, ningu\u00e9m menos que o surfista Gabriel Medina, estar hospedado por l\u00e1. Rafaella, irm\u00e3 de Neymar, Gabigol do flamengo, Lucas Lima, do Palmeiras e Rafael Zulu integram parte do grupo do jogador<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parece que Neymar Jr. j\u00e1 tem uma tradi\u00e7\u00e3o para o R\u00e9veillon: pelo terceiro ano consecutivo, o jogador deve passar a virada de ano em Barra Grande, na Pen\u00ednsula de Mara\u00fa.&nbsp;O atacante do Paris Saint Germain (PSG) j\u00e1 chegou a Taipu de Fora e est\u00e1 mais uma vez hospedado na mans\u00e3o do publicit\u00e1rio Duda Mendon\u00e7a.&nbsp; &nbsp; E, para receber o novo ano como se deve, claro, o craque do PSG, j\u00e1 garantiu a presen\u00e7a dos insepar\u00e1veis par\u00e7as. Entre eles ningu\u00e9m mais, ningu\u00e9m menos que o surfista Gabriel Medina, estar hospedado por l\u00e1. Rafaella, irm\u00e3 de Neymar, Gabigol do flamengo, Lucas Lima, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":120521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[26,29,17,18,21,22],"tags":[1978,596],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/120524"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=120524"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/120524\/revisions"}],"predecessor-version":[{"id":120525,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/120524\/revisions\/120525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/120521"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=120524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=120524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=120524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}