{"id":120505,"date":"2019-12-27T03:01:46","date_gmt":"2019-12-27T06:01:46","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=120505"},"modified":"2019-12-27T03:01:46","modified_gmt":"2019-12-27T06:01:46","slug":"marau-secretario-de-turismo-da-bahia-estara-presente-no-reveillon-mil-sorrisos-em-barra-grande","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/12\/27\/marau-secretario-de-turismo-da-bahia-estara-presente-no-reveillon-mil-sorrisos-em-barra-grande\/","title":{"rendered":"Mara\u00fa: Secret\u00e1rio de Turismo da Bahia estar\u00e1 presente no r\u00e9veillon Mil Sorrisos em Barra Grande"},"content":{"rendered":"<div id=\"attachment_120388\" style=\"width: 591px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-120388\" loading=\"lazy\" class=\" wp-image-120388\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-19-at-15.17.51-1-1.jpeg\" alt=\"\" width=\"581\" height=\"415\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-19-at-15.17.51-1-1.jpeg 599w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-19-at-15.17.51-1-1-300x214.jpeg 300w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/><p id=\"caption-attachment-120388\" class=\"wp-caption-text\"><strong>Secret\u00e1rio de Turismo da Bahia, Fausto Fraco ao lado da prefeita Gracinha Viana.<\/strong><\/p><\/div>\n<p>Fausto Franco, Secret\u00e1rio de Turismo da Bahia, estar\u00e1 presente em Barra Grande no r\u00e9veillon Mil Sorrisos. Esta ser\u00e1 a primeira vez que um Secret\u00e1rio de turismo do estado vem \u00e0 Pen\u00ednsula de Mara\u00fa na virada de ano. O titular do turismo no estado, vem demonstrando a import\u00e2ncia tur\u00edstica de Barra Grande no c\u00e9nario estadual.<\/p>\n<p>Fausto j\u00e1 esteve no m\u00ednimo quatro vezes no distrito desde que assumiu a pasta.&nbsp;Considerado um dos Secret\u00e1rios mais atuantes do Governador Rui Costa, Fausto Franco, esteve juntamente com o Deputado Eduardo Salles no \u00faltimo dia, 19, em Barra Grande, na viagem inaugural do Catamar\u00e3 que faz a travessia Salvador a Barra Grande com parada em Morro de S\u00e3o Paulo.<\/p>\n<p>O chefe do turismo baiano tamb\u00e9m deve estar presente no r\u00e9veillon Mil Sorrisos que re\u00fane celebridades e atletas conhecidos mundialmente como \u00e9 o craque Neymar e o bicampe\u00e3o de surf, Gabriel Medina.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fausto Franco, Secret\u00e1rio de Turismo da Bahia, estar\u00e1 presente em Barra Grande no r\u00e9veillon Mil Sorrisos. Esta ser\u00e1 a primeira vez que um Secret\u00e1rio de turismo do estado vem \u00e0 Pen\u00ednsula de Mara\u00fa na virada de ano. O titular do turismo no estado, vem demonstrando a import\u00e2ncia tur\u00edstica de Barra Grande no c\u00e9nario estadual. Fausto j\u00e1 esteve no m\u00ednimo quatro vezes no distrito desde que assumiu a pasta.&nbsp;Considerado um dos Secret\u00e1rios mais atuantes do Governador Rui Costa, Fausto Franco, esteve juntamente com o Deputado Eduardo Salles no \u00faltimo dia, 19, em Barra Grande, na viagem inaugural do Catamar\u00e3 que faz [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":120388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,26,29,17,18,23,28,22],"tags":[1970],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/120505"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=120505"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/120505\/revisions"}],"predecessor-version":[{"id":120506,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/120505\/revisions\/120506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/120388"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=120505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=120505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=120505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}