{"id":119801,"date":"2019-11-01T18:15:42","date_gmt":"2019-11-01T21:15:42","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=119801"},"modified":"2019-11-01T18:15:42","modified_gmt":"2019-11-01T21:15:42","slug":"marau-piscinas-naturais-de-taipu-de-fora-sao-limpas-apos-aparecimento-de-fragmentos-de-oleo","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/11\/01\/marau-piscinas-naturais-de-taipu-de-fora-sao-limpas-apos-aparecimento-de-fragmentos-de-oleo\/","title":{"rendered":"Mara\u00fa: Piscinas naturais de Taipu de Fora s\u00e3o limpas ap\u00f3s aparecimento de fragmentos de \u00f3leo"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-119802 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-01-at-10.43.46-1.jpeg\" alt=\"\" width=\"586\" height=\"330\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-01-at-10.43.46-1.jpeg 600w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-01-at-10.43.46-1-300x169.jpeg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/p>\n<p>Do G1 BA<\/p>\n<p>As manchas de \u00f3leo que atingem o litoral da Bahia chegaram \u00e0s piscinas naturais de Taipu de Fora, na cidade de Mara\u00fa, baixo sul da Bahia, nesta sexta-feira (1\u00ba). A praia \u00e9 conhecida pelas \u00e1guas cristalinas e \u00e9 a principal atra\u00e7\u00e3o tur\u00edstica da pen\u00ednsula do munic\u00edpio.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"46\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A prefeitura de Mara\u00fa come\u00e7ou a fazer a remo\u00e7\u00e3o dos fragmentos desde o in\u00edcio da manh\u00e3, e conta com a ajuda de volunt\u00e1rios que est\u00e3o no local. Ainda n\u00e3o h\u00e1 um balan\u00e7o da quantidade de \u00f3leo removido.&nbsp;<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A Pol\u00edcia Federal identificou, tamb\u00e9m nesta sexta,&nbsp;um navio de bandeira grega que \u00e9 suspeito de ser o respons\u00e1vel pelo derramamento do \u00f3leo no litoral nordestino. Mandados de pris\u00e3o expedidos no Rio Grande do Norte est\u00e3o sendo cumpridos no Rio de Janeiro.<\/p>\n<\/div>\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"7\">\n<div class=\"mc-column content-media__container\">\n<div class=\"progressive-img can-open-lightbox\" data-min-size=\"1008x567\" data-min-size-url=\"https:\/\/s2.glbimg.com\/5WUutTapinS3fItpCKKD4ucoTT8=\/0x0:1920x1080\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/P\/E\/WJ5ZBwQC2G57vOixNwXw\/whatsapp-image-2019-11-01-at-10.46.27.jpeg\" data-max-size=\"1600x900\" data-max-size-url=\"https:\/\/s2.glbimg.com\/gKuRc0ZH1x8UNUJvtFFTjPp44fg=\/0x0:1920x1080\/1600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/P\/E\/WJ5ZBwQC2G57vOixNwXw\/whatsapp-image-2019-11-01-at-10.46.27.jpeg\" data-media-index=\"0\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"5\">\n<div id=\"banner_materia2\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia2 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-id=\"banner_materia2\" data-google-query-id=\"CLiNysn0yeUCFY3I4wcdC-YEow\" data-cid=\"138293216632\" data-lid=\"5212445963\">&nbsp;<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Do G1 BA As manchas de \u00f3leo que atingem o litoral da Bahia chegaram \u00e0s piscinas naturais de Taipu de Fora, na cidade de Mara\u00fa, baixo sul da Bahia, nesta sexta-feira (1\u00ba). A praia \u00e9 conhecida pelas \u00e1guas cristalinas e \u00e9 a principal atra\u00e7\u00e3o tur\u00edstica da pen\u00ednsula do munic\u00edpio. A prefeitura de Mara\u00fa come\u00e7ou a fazer a remo\u00e7\u00e3o dos fragmentos desde o in\u00edcio da manh\u00e3, e conta com a ajuda de volunt\u00e1rios que est\u00e3o no local. Ainda n\u00e3o h\u00e1 um balan\u00e7o da quantidade de \u00f3leo removido.&nbsp; A Pol\u00edcia Federal identificou, tamb\u00e9m nesta sexta,&nbsp;um navio de bandeira grega que \u00e9 suspeito [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17,18,19],"tags":[1778],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119801"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=119801"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119801\/revisions"}],"predecessor-version":[{"id":119803,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119801\/revisions\/119803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/119802"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=119801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=119801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=119801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}