{"id":119702,"date":"2019-10-28T02:46:08","date_gmt":"2019-10-28T05:46:08","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=119702"},"modified":"2019-10-28T02:46:08","modified_gmt":"2019-10-28T05:46:08","slug":"marau-mais-de-300-voluntarios-ja-foram-treinados-pela-oceanpact-para-limpeza-das-praias-em-barra-grande","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/10\/28\/marau-mais-de-300-voluntarios-ja-foram-treinados-pela-oceanpact-para-limpeza-das-praias-em-barra-grande\/","title":{"rendered":"Mara\u00fa: Mais de 300 volunt\u00e1rios j\u00e1 foram treinados pela Oceanpact para limpeza das praias em Barra Grande"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-119705 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.26.jpeg\" alt=\"\" width=\"585\" height=\"371\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.26.jpeg 926w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.26-300x190.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.26-768x487.jpeg 768w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/p>\n<p class=\"single-post__entry-title\">A<strong> OceanPact<\/strong>, empresa brasileira de navega\u00e7\u00e3o especializada no gerenciamento e resposta a emerg\u00eancia em \u00e1reas costeiras e offshore com foco principal em prote\u00e7\u00e3o ambiental, realizou treinamento t\u00e9cnico e de forma gratuita para moradores da Pen\u00ednsula de Mara\u00fa, visando capacitar volunt\u00e1rios no combate ao \u00f3leo nas praias.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-119704 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.07.jpeg\" alt=\"\" width=\"588\" height=\"441\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.07.jpeg 1032w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.07-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.07-768x576.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-28-at-02.42.07-1024x768.jpeg 1024w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/p>\n<p>Mais de 300 volunt\u00e1rios foram treinados pela empresa em toda pen\u00ednsula, e a empresa segue com profissionais em Barra Grande para ajudar na limpeza das praias.&nbsp;A iniciativa vem reunindo multiplicadores, como as associa\u00e7\u00f5es, para sensibilizar comerciantes, banhistas, turistas e moradores sobre o que fazer caso manchas de petr\u00f3leo cru cheguem \u00e0 costa marauense.<\/p>\n<p>O treinamento tamb\u00e9m serviu para alertar a respeito dos perigos do contato com o material contaminante. Na oportunidade, foram discutidas a\u00e7\u00f5es de preven\u00e7\u00e3o, limpezas e preserva\u00e7\u00e3o de praias do munic\u00edpio.&nbsp;Criada em 2007, a OceanPact se tornou a maior e mais completa empresa de Resposta a derramamento de \u00f3leo da Am\u00e9rica Latina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A OceanPact, empresa brasileira de navega\u00e7\u00e3o especializada no gerenciamento e resposta a emerg\u00eancia em \u00e1reas costeiras e offshore com foco principal em prote\u00e7\u00e3o ambiental, realizou treinamento t\u00e9cnico e de forma gratuita para moradores da Pen\u00ednsula de Mara\u00fa, visando capacitar volunt\u00e1rios no combate ao \u00f3leo nas praias. Mais de 300 volunt\u00e1rios foram treinados pela empresa em toda pen\u00ednsula, e a empresa segue com profissionais em Barra Grande para ajudar na limpeza das praias.&nbsp;A iniciativa vem reunindo multiplicadores, como as associa\u00e7\u00f5es, para sensibilizar comerciantes, banhistas, turistas e moradores sobre o que fazer caso manchas de petr\u00f3leo cru cheguem \u00e0 costa marauense. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,26,29,17,18,27,28],"tags":[265,1752],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119702"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=119702"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119702\/revisions"}],"predecessor-version":[{"id":119706,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119702\/revisions\/119706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/119704"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=119702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=119702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=119702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}