{"id":119644,"date":"2019-10-23T01:54:55","date_gmt":"2019-10-23T04:54:55","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=119644"},"modified":"2019-10-23T01:54:55","modified_gmt":"2019-10-23T04:54:55","slug":"empresa-de-simoes-filho-vence-pregao-do-dnit-para-recuperacao-da-br-030-na-peninsula-de-marau","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/10\/23\/empresa-de-simoes-filho-vence-pregao-do-dnit-para-recuperacao-da-br-030-na-peninsula-de-marau\/","title":{"rendered":"Empresa de Sim\u00f5es Filho vence preg\u00e3o do DNIT para recupera\u00e7\u00e3o da BR-030 na Pen\u00ednsula de Mara\u00fa"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-119444 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/dnit.png\" alt=\"\" width=\"588\" height=\"231\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/dnit.png 830w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/dnit-300x117.png 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/dnit-768x301.png 768w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/p>\n<p>A empresa que dever\u00e1 ser respons\u00e1vel pela manuten\u00e7\u00e3o da BR-030, entre Ubaitaba a Campinhos, em Mara\u00fa, j\u00e1 \u00e9 conhecida. A&nbsp;<strong>PAVISERVICE SERVICOS DE PAVIMENTACAO LTDA<\/strong>, foi a vencedora do preg\u00e3o eletr\u00f4nico do Departamento Nacional de Infraestrutura de Transporte<span class=\"textexposedshow\">s (Dnit) na manh\u00e3 da \u00faltima ter\u00e7a-feira, 22.<\/span><\/p>\n<p><span class=\"textexposedshow\">O valor da proposta foi de R$ 16.800.000, abaixo do pre\u00e7o estimado que era de 31 milh\u00f5es. De acordo com o Dnit, \u00e9 at\u00e9 amanh\u00e3 dia 23\/10\/2019 \u00e0s 10:50, a empresa dever\u00e1 entregar presencialmente os documentos, que ser\u00e3o analisados. Caso n\u00e3o haja recurso administrativo, a proposta \u00e9 liberada.&nbsp;<\/span>Ao todo, 39 empresas registraram proposta.&nbsp;<\/p>\n<p>Agora, de acordo com o que prev\u00ea o DNIT, falta apenas a abertura do envelope de habilita\u00e7\u00e3o. No caso da Paviservice, ser\u00e1 apenas uma formalidade, j\u00e1 que ela j\u00e1 possui contratos com o \u00f3rg\u00e3o em rodovias federais na Bahia.<\/p>\n<p>Em contato com o portal <strong>Barra Grande 24h<\/strong>, o Superintendente do DNIT, Amauri Lima, disse que a empresa j\u00e1 possui quatro contratos em rodovias como as BR-242, BR-020, BR-030, em Malhada e na BR-101, todas na Bahia e a empresa vem realizando bons servi\u00e7os nestas rodovias.<\/p>\n<p><strong>A EMPRESA<\/strong><\/p>\n<p>Fundada em 1996 como uma construtora voltada para a manuten\u00e7\u00e3o rodovi\u00e1ria e sua sede est\u00e1 situada na Avenida Universit\u00e1ria, n\u00ba 1.200, CIA II, Sim\u00f5es Filho, Bahia.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A empresa que dever\u00e1 ser respons\u00e1vel pela manuten\u00e7\u00e3o da BR-030, entre Ubaitaba a Campinhos, em Mara\u00fa, j\u00e1 \u00e9 conhecida. A&nbsp;PAVISERVICE SERVICOS DE PAVIMENTACAO LTDA, foi a vencedora do preg\u00e3o eletr\u00f4nico do Departamento Nacional de Infraestrutura de Transportes (Dnit) na manh\u00e3 da \u00faltima ter\u00e7a-feira, 22. O valor da proposta foi de R$ 16.800.000, abaixo do pre\u00e7o estimado que era de 31 milh\u00f5es. De acordo com o Dnit, \u00e9 at\u00e9 amanh\u00e3 dia 23\/10\/2019 \u00e0s 10:50, a empresa dever\u00e1 entregar presencialmente os documentos, que ser\u00e3o analisados. Caso n\u00e3o haja recurso administrativo, a proposta \u00e9 liberada.&nbsp;Ao todo, 39 empresas registraram proposta.&nbsp; Agora, de acordo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,26,29,17,18,27,28,22],"tags":[1733],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119644"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=119644"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119644\/revisions"}],"predecessor-version":[{"id":119645,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119644\/revisions\/119645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/119444"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=119644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=119644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=119644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}