{"id":119522,"date":"2019-10-17T11:34:46","date_gmt":"2019-10-17T14:34:46","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=119522"},"modified":"2019-10-17T11:34:46","modified_gmt":"2019-10-17T14:34:46","slug":"itubera-3-presos-armas-e-drogas-apreendidas-em-operacao-conjunta-das-policias-civil-e-militar","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/10\/17\/itubera-3-presos-armas-e-drogas-apreendidas-em-operacao-conjunta-das-policias-civil-e-militar\/","title":{"rendered":"Ituber\u00e1: 3 presos, armas e drogas apreendidas em opera\u00e7\u00e3o conjunta das Pol\u00edcias Civil e Militar"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-119523 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op1-768x427.jpg\" alt=\"\" width=\"585\" height=\"325\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op1-768x427.jpg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op1-768x427-300x167.jpg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/p>\n<p>Do <strong>Portal Pratigi<\/strong><\/p>\n<p>Uma opera\u00e7\u00e3o conjunta da 5\u00aa Coorpin \u2013 Coordenadoria Regional do Interior e 33\u00aa CIPM \u2013 Companhia Independente da Pol\u00edcia Militar\/Valen\u00e7a, na manh\u00e3 desta quinta-feira (17), em Ituber\u00e1, no Baixo Sul, movimentou cerca de 80 policiais para o cumprimento de mandados de pris\u00e3o, busca e apreens\u00e3o na cidade.<\/p>\n<p>A opera\u00e7\u00e3o come\u00e7ou por volta das 5h40 da manh\u00e3 e contou com o apoio do Graer \u2013 Grupamento A\u00e9reo da Pol\u00edcia Militar da Bahia, que sobrevoou a cidade, mais precisamente o Bairro da Prainha 2, em suporte aos agentes em terra que estavam em cerca de 20 viaturas da PM, (Cipe Cacaueira) Caerc, Rondesp Sul e COE \u2013 Comando de Opera\u00e7\u00f5es Especiais da Pol\u00edcia Civil.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-119525 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op5-768x427.jpg\" alt=\"\" width=\"583\" height=\"324\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op5-768x427.jpg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op5-768x427-300x167.jpg 300w\" sizes=\"(max-width: 583px) 100vw, 583px\" \/><\/p>\n<p>De acordo com o coordenador da 5\u00aa Coorpin, delegado Jos\u00e9 Raimundo, duas quadrilhas rivais estavam sendo investigadas pela justi\u00e7a, que por sua vez, decretou os mandados. \u201cN\u00f3s j\u00e1 est\u00e1vamos investigando, h\u00e1 pelo menos quatro meses, a quadrilha do \u201cV\u00e9io\u201d, composta por cerca de 30 criminosos e, tamb\u00e9m, a quadrilha do \u201cZ\u00e3o\u201d, que vem rivalizando, se matando e tirando a paz do povo ituberanese. Conseguimos levantar alguns alvos nas localidades da Prainha 1, 2 e Pedreiras, \u00e1reas lideradas pelo \u201cV\u00e9io\u201d, afirmou o delegado.<\/p>\n<p>No total foram treze mandados de busca e apreens\u00e3o e tr\u00eas mandados de pris\u00e3o preventiva decretados pelo Poder Judici\u00e1rio de Ituber\u00e1. A opera\u00e7\u00e3o foi realizada com um efetivo de 50 policiais civis e 30 policiais militares.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-119524 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op2-768x427.jpg\" alt=\"\" width=\"586\" height=\"326\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op2-768x427.jpg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op2-768x427-300x167.jpg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/p>\n<p>Foram presos em flagrante Denis Ferreira dos Santos, o \u201cFazendeiro\u201d, preso em posse de um rev\u00f3lver calibre .38, com seis cartuchos intactos, certa quantidade de maconha e dinheiro proveniente do tr\u00e1fico. Al\u00e9m de Denis, foi preso por associa\u00e7\u00e3o criminosa, um homem de prenome Abr\u00e3o, tamb\u00e9m integrante da quadrilha, e Wagner Santos Sodr\u00e9.<\/p>\n<p>Na casa de outro integrante da quadrilha, Max Concei\u00e7\u00e3o dos Santos, que n\u00e3o foi localizado, a pol\u00edcia encontrou 37 pedras de crack, balan\u00e7a de precis\u00e3o, embalagem para droga, maconha e dois rel\u00f3gios de luxo.<\/p>\n<p>Todos foram encaminhados para Valen\u00e7a onde ficar\u00e3o \u00e0 disposi\u00e7\u00e3o da justi\u00e7a para audi\u00eancia de cust\u00f3dia e se tiverem a pris\u00e3o em flagrante convertida em pris\u00e3o preventiva, eles ser\u00e3o encaminhados para o pres\u00eddio de Valen\u00e7a onde aguardar\u00e3o julgamento.<\/p>\n<p>Ou\u00e7a a sonora com as avalia\u00e7\u00f5es do Delegado Dr. Jos\u00e9 Raimundo e do Ten. Cel. Alexandre Souza:<\/p>\n<p>\u201cEssa \u00e9 uma resposta a essa rivalidade entre essas quadrilhas. Eles v\u00eam se matando e trazendo p\u00e2nico \u00e0 sociedade e nossa finalidade \u00e9 tirar esses criminosos de circula\u00e7\u00e3o, prend\u00ea-los para que a paz possa reinar definitivamente em Ituber\u00e1\u201d.&nbsp;A avalia\u00e7\u00e3o foi positiva e informo que o trabalho vai continuar. Quero agradecer ao apoio da Pol\u00edcia Militar, do Judici\u00e1rio, do Minist\u00e9rio P\u00fablico, da administra\u00e7\u00e3o municipal que tem dado todo o apoio poss\u00edvel para que a gente possa junto com o governo do Estado desenvolver esse trabalho\u201d, finalizou o delegado Dr. Jos\u00e9 Raimundo.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-119526 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op6-1.jpg\" alt=\"\" width=\"589\" height=\"328\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op6-1.jpg 600w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/op6-1-300x167.jpg 300w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><\/p>\n<p>O Ten. Cel. Alexandre Costa, Comandante da 33\u00aa CIPM disse que a opera\u00e7\u00e3o foi exitosa e reflete o compromisso das autoridades policiais com a seguran\u00e7a da popula\u00e7\u00e3o de Ituber\u00e1. \u201cOpera\u00e7\u00e3o ocorreu com \u00eaxito com pris\u00e3o e tr\u00eas elementos, al\u00e9m de drogas e armas. Isso mostra a uni\u00e3o das pol\u00edcias Militar e Civil, juntas em prol da seguran\u00e7a p\u00fablica. Quero tranquilizar a comunidade e afirmo que as pol\u00edcias est\u00e3o juntas. Contem com a Pol\u00edcia Militar, contem com a Pol\u00edcia Civil, denunciem que a pol\u00edcias est\u00e3o a\u00ed para dar essa resposta \u00e0 sociedade, como fizemos hoje\u201d, destacou o Ten. Cel. Alexandre Souza.<\/p>\n<p>Imagens: 33\u00aa CIPM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Portal Pratigi Uma opera\u00e7\u00e3o conjunta da 5\u00aa Coorpin \u2013 Coordenadoria Regional do Interior e 33\u00aa CIPM \u2013 Companhia Independente da Pol\u00edcia Militar\/Valen\u00e7a, na manh\u00e3 desta quinta-feira (17), em Ituber\u00e1, no Baixo Sul, movimentou cerca de 80 policiais para o cumprimento de mandados de pris\u00e3o, busca e apreens\u00e3o na cidade. A opera\u00e7\u00e3o come\u00e7ou por volta das 5h40 da manh\u00e3 e contou com o apoio do Graer \u2013 Grupamento A\u00e9reo da Pol\u00edcia Militar da Bahia, que sobrevoou a cidade, mais precisamente o Bairro da Prainha 2, em suporte aos agentes em terra que estavam em cerca de 20 viaturas da PM, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119526,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[29,17,19,3],"tags":[1706,1705],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119522"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=119522"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119522\/revisions"}],"predecessor-version":[{"id":119527,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119522\/revisions\/119527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/119526"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=119522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=119522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=119522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}