{"id":119362,"date":"2019-10-11T17:45:29","date_gmt":"2019-10-11T20:45:29","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=119362"},"modified":"2019-10-11T17:45:29","modified_gmt":"2019-10-11T20:45:29","slug":"secretaria-de-agricultura-de-marau-entrega-kits-irrigacao-e-beneficia-agricultores-familiares-na-santa-maria","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/10\/11\/secretaria-de-agricultura-de-marau-entrega-kits-irrigacao-e-beneficia-agricultores-familiares-na-santa-maria\/","title":{"rendered":"Secretaria de Agricultura de Mara\u00fa entrega kits irriga\u00e7\u00e3o e beneficia agricultores familiares na Santa Maria"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-119439 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.18-1.jpeg\" alt=\"\" width=\"581\" height=\"327\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.18-1.jpeg 1280w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.18-1-300x169.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.18-1-768x432.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.18-1-1024x576.jpeg 1024w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/><\/p>\n<p>A produ\u00e7\u00e3o rural do munic\u00edpio de Mara\u00fa ganhou refor\u00e7o, na \u00faltima quinta-feira (10), com a entrega&nbsp;de kits de irriga\u00e7\u00e3o&nbsp; aos produtores da Associa\u00e7\u00e3o de Jovens Agricultores do P. A. Santa Maria.&nbsp;De acorco com o Secret\u00e1rio, s\u00e3o vinte agricultores beneficiados para realizarem o cultivo de cacau em uma \u00e1rea equivalente a 1 hectare.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-119440 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.17-1.jpeg\" alt=\"\" width=\"588\" height=\"339\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.17-1.jpeg 600w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-11-at-17.41.17-1-300x173.jpeg 300w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/p>\n<p>A a\u00e7\u00e3o foi promovida pela Secretaria de Agricultura do munic\u00edpio em parceria com a associa\u00e7\u00e3o e contou com a presen\u00e7a da Prefeita Gracinha Viana, do Secret\u00e1rio de agricultura, Valdemir Lisboa e do Presidente da C\u00e2mara, vereador Manass\u00e9s.&nbsp; Gracinha,&nbsp; falou da satisfa\u00e7\u00e3o em participar do Ato e celebrar a entrega de equipamentos que v\u00e3o garantir dias promissores para agricultura familiar local.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO recebimento dos kits de irriga\u00e7\u00e3o v\u00e3o trazer in\u00fameros benef\u00edcios para os nossos agricultores, que esperam ansiosos para poderem produzir mais e aumentar a renda das fam\u00edlias\u201d, ressalta a prefeita Gracinha Viana.<\/p>\n<p>Esse \u00e9 mais um projeto do Governo do Estado em Parceria com a Prefeitura de Mara\u00fa, na busca de desenvolvimento e sustentabilidade para os agricultores marauenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A produ\u00e7\u00e3o rural do munic\u00edpio de Mara\u00fa ganhou refor\u00e7o, na \u00faltima quinta-feira (10), com a entrega&nbsp;de kits de irriga\u00e7\u00e3o&nbsp; aos produtores da Associa\u00e7\u00e3o de Jovens Agricultores do P. A. Santa Maria.&nbsp;De acorco com o Secret\u00e1rio, s\u00e3o vinte agricultores beneficiados para realizarem o cultivo de cacau em uma \u00e1rea equivalente a 1 hectare. A a\u00e7\u00e3o foi promovida pela Secretaria de Agricultura do munic\u00edpio em parceria com a associa\u00e7\u00e3o e contou com a presen\u00e7a da Prefeita Gracinha Viana, do Secret\u00e1rio de agricultura, Valdemir Lisboa e do Presidente da C\u00e2mara, vereador Manass\u00e9s.&nbsp; Gracinha,&nbsp; falou da satisfa\u00e7\u00e3o em participar do Ato e celebrar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119440,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26,29,17,18,1,27],"tags":[1674],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119362"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=119362"}],"version-history":[{"count":3,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119362\/revisions"}],"predecessor-version":[{"id":119441,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/119362\/revisions\/119441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/119440"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=119362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=119362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=119362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}