{"id":118670,"date":"2019-09-06T02:22:37","date_gmt":"2019-09-06T05:22:37","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=118670"},"modified":"2019-09-06T02:22:37","modified_gmt":"2019-09-06T05:22:37","slug":"jovens-do-servico-de-convivencia-de-marau-participam-de-conferencia-do-direitos-da-criancas-em-itabuna","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/09\/06\/jovens-do-servico-de-convivencia-de-marau-participam-de-conferencia-do-direitos-da-criancas-em-itabuna\/","title":{"rendered":"Jovens do Servi\u00e7o de Conviv\u00eancia de Mara\u00fa participam de Confer\u00eancia do Direitos da Crian\u00e7as em Itabuna"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-118671 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.11.jpeg\" alt=\"\" width=\"588\" height=\"441\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.11.jpeg 1152w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.11-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.11-768x576.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.11-1024x768.jpeg 1024w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/p>\n<p>No dia 3 de Setembro do ano corrente, a Prefeitura Municipal de Mara\u00fa, por meio do CRAS , atrav\u00e9s do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos (SCFV), participou da Confer\u00eancia Territorial do Direitos da Crian\u00e7a e do Adolescente, realizada no audit\u00f3rio da Faculdade de Tecnologias e Ci\u00eancias (FTC) de Itabuna.<\/p>\n<p><img loading=\"lazy\" class=\" wp-image-118672 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.10-1.jpeg\" alt=\"\" width=\"575\" height=\"431\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.10-1.jpeg 600w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-04-at-13.25.10-1-300x225.jpeg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/p>\n<p>No evento, as crian\u00e7as realizaram apresenta\u00e7\u00f5es das atividades aprendidas nas oficinas do SCFV, como a de flauta, emocionando os mais de 17 munic\u00edpios ali representados. Uma das crian\u00e7as da cidade, foi convidada a comp\u00f4r a mesa, junto as autoridades ali presentes.&nbsp;As delegadas e delegados do munic\u00edpio, participaram das discuss\u00f5es nos eixos tem\u00e1ticos que, no geral, tratavam sobre a prote\u00e7\u00e3o social dos direitos dos jovens, considerando princ\u00edpios como liberdade, dignidade, equidade.<\/p>\n<p>No final, dois delegados ir\u00e3o representar nossas demandas na Confer\u00eancia Estadual, que ocorrer\u00e1 ainda este ano. Estes fatos, s\u00e3o resultado de um trabalho respons\u00e1vel, realizado pela Prefeitura Municipal de Mara\u00fa e Secretaria de Desenvolvimento Social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 3 de Setembro do ano corrente, a Prefeitura Municipal de Mara\u00fa, por meio do CRAS , atrav\u00e9s do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos (SCFV), participou da Confer\u00eancia Territorial do Direitos da Crian\u00e7a e do Adolescente, realizada no audit\u00f3rio da Faculdade de Tecnologias e Ci\u00eancias (FTC) de Itabuna. No evento, as crian\u00e7as realizaram apresenta\u00e7\u00f5es das atividades aprendidas nas oficinas do SCFV, como a de flauta, emocionando os mais de 17 munic\u00edpios ali representados. Uma das crian\u00e7as da cidade, foi convidada a comp\u00f4r a mesa, junto as autoridades ali presentes.&nbsp;As delegadas e delegados do munic\u00edpio, participaram das discuss\u00f5es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":118672,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29,17,20,23,27],"tags":[1544],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/118670"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=118670"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/118670\/revisions"}],"predecessor-version":[{"id":118673,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/118670\/revisions\/118673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/118672"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=118670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=118670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=118670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}