{"id":118666,"date":"2019-09-06T01:01:39","date_gmt":"2019-09-06T04:01:39","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=118666"},"modified":"2019-09-06T01:01:39","modified_gmt":"2019-09-06T04:01:39","slug":"programa-primeira-infancia-promoveu-mutirao-para-emissao-de-rg-em-marau","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/09\/06\/programa-primeira-infancia-promoveu-mutirao-para-emissao-de-rg-em-marau\/","title":{"rendered":"Programa Primeira Inf\u00e2ncia promoveu mutir\u00e3o para emiss\u00e3o de RG em Mara\u00fa"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-118668 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-08.12.21.jpeg\" alt=\"\" width=\"588\" height=\"441\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-08.12.21.jpeg 1032w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-08.12.21-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-08.12.21-768x576.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-08.12.21-1024x768.jpeg 1024w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/p>\n<p>A Secretaria de Desenvolvimento Social e CRAS por meio do Programa Primeira Inf\u00e2ncia no SUAS- Crian\u00e7a Feliz, promoveu no dia 02 deste m\u00eas um mutir\u00e3o para emiss\u00e3o de carteiras de identidade das crian\u00e7as acompanhadas pelo programa. O RG \u00e9 um documento que garante seguran\u00e7a para a crian\u00e7a em todas as situa\u00e7\u00f5es que requerem a identifica\u00e7\u00e3o. Foram atendidas 12 crian\u00e7as da Sede do munic\u00edpio, outras crian\u00e7as acompanhadas nos povoados tamb\u00e9m ser\u00e3o beneficiados com o servi\u00e7o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Desenvolvimento Social e CRAS por meio do Programa Primeira Inf\u00e2ncia no SUAS- Crian\u00e7a Feliz, promoveu no dia 02 deste m\u00eas um mutir\u00e3o para emiss\u00e3o de carteiras de identidade das crian\u00e7as acompanhadas pelo programa. O RG \u00e9 um documento que garante seguran\u00e7a para a crian\u00e7a em todas as situa\u00e7\u00f5es que requerem a identifica\u00e7\u00e3o. Foram atendidas 12 crian\u00e7as da Sede do munic\u00edpio, outras crian\u00e7as acompanhadas nos povoados tamb\u00e9m ser\u00e3o beneficiados com o servi\u00e7o.<\/p>\n","protected":false},"author":2,"featured_media":118668,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17,18,19,27],"tags":[1543],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/118666"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=118666"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/118666\/revisions"}],"predecessor-version":[{"id":118669,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/118666\/revisions\/118669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/118668"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=118666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=118666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=118666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}