{"id":117020,"date":"2019-05-23T20:10:36","date_gmt":"2019-05-23T23:10:36","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=117020"},"modified":"2019-05-23T20:10:36","modified_gmt":"2019-05-23T23:10:36","slug":"porto-seguro-tres-indios-sao-baleados-apos-invasao-a-aldeia-pataxo","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/05\/23\/porto-seguro-tres-indios-sao-baleados-apos-invasao-a-aldeia-pataxo\/","title":{"rendered":"Porto Seguro: Tr\u00eas \u00edndios s\u00e3o baleados ap\u00f3s invas\u00e3o \u00e0 aldeia patax\u00f3"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-117021 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/05\/1558643765imagem-noticia-5.jpg\" alt=\"\" width=\"567\" height=\"378\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/05\/1558643765imagem-noticia-5.jpg 800w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/05\/1558643765imagem-noticia-5-300x200.jpg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/05\/1558643765imagem-noticia-5-768x512.jpg 768w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><\/p>\n<p>Tr\u00eas \u00edndios foram baleados em um ataque \u00e0 aldeia patax\u00f3 Barra Velha em Porto Seguro, na Costa do Descobrimento. Segundo o G1, o fato ocorreu na noite desta quarta-feira (22), por volta das 20h, ap\u00f3s seis homens invadirem a aldeia \u00e0 procura de um homem, que n\u00e3o foi encontrado pelo grupo.<\/p>\n<p>Uma escola chegou a ser atingida por diversos tiros. De acordo com a Funai [Funda\u00e7\u00e3o Nacional do \u00cdndio], as v\u00edtimas foram encaminhadas para hospitais da regi\u00e3o. N\u00e3o h\u00e1 mais informa\u00e7\u00f5es sobre o estado de sa\u00fade deles. A Pol\u00edcia Civil local investiga a autoria e a motiva\u00e7\u00e3o do crime. (Bahia Not\u00edcias)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas \u00edndios foram baleados em um ataque \u00e0 aldeia patax\u00f3 Barra Velha em Porto Seguro, na Costa do Descobrimento. Segundo o G1, o fato ocorreu na noite desta quarta-feira (22), por volta das 20h, ap\u00f3s seis homens invadirem a aldeia \u00e0 procura de um homem, que n\u00e3o foi encontrado pelo grupo. Uma escola chegou a ser atingida por diversos tiros. De acordo com a Funai [Funda\u00e7\u00e3o Nacional do \u00cdndio], as v\u00edtimas foram encaminhadas para hospitais da regi\u00e3o. N\u00e3o h\u00e1 mais informa\u00e7\u00f5es sobre o estado de sa\u00fade deles. A Pol\u00edcia Civil local investiga a autoria e a motiva\u00e7\u00e3o do crime. (Bahia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":117021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17,1],"tags":[1137],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/117020"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=117020"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/117020\/revisions"}],"predecessor-version":[{"id":117022,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/117020\/revisions\/117022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/117021"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=117020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=117020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=117020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}