{"id":115829,"date":"2019-02-26T23:14:21","date_gmt":"2019-02-27T02:14:21","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=115829"},"modified":"2019-02-27T08:38:36","modified_gmt":"2019-02-27T11:38:36","slug":"idoso-e-morto-a-facadas-durante-briga-na-zona-rural-de-marau","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/02\/26\/idoso-e-morto-a-facadas-durante-briga-na-zona-rural-de-marau\/","title":{"rendered":"Idoso \u00e9 morto a facadas durante briga na zona rural de Mara\u00fa"},"content":{"rendered":"<div class=\"title\">\n<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"42\" data-block-id=\"1\">\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><img loading=\"lazy\" class=\"wp-image-115832 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59.jpeg\" alt=\"\" width=\"573\" height=\"399\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59.jpeg 960w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59-300x209.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59-768x535.jpeg 768w\" sizes=\"(max-width: 573px) 100vw, 573px\" \/><\/p>\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">Um idoso de 65 anos foi morto a facadas durante uma briga nesta ter\u00e7a-feira (26). O suspeito do assassinato foi linchado pela popula\u00e7\u00e3o que&nbsp; se revoltou com o crime. O caso ocorreu no povoado do Quitungo, na zona rural de Mara\u00fa. O idoso identificado por Valtemiro Paulo da Cruz, foi encontrado morto no sof\u00e1 por populares.<\/p>\n<div id=\"attachment_115830\" style=\"width: 502px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-115830\" loading=\"lazy\" class=\"size-full wp-image-115830\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59-1.jpeg\" alt=\"\" width=\"492\" height=\"356\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59-1.jpeg 492w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-23.08.59-1-300x217.jpeg 300w\" sizes=\"(max-width: 492px) 100vw, 492px\" \/><p id=\"caption-attachment-115830\" class=\"wp-caption-text\">Idoso foi morto a facadas no povoado do Quitungo, na zona rural de Mara\u00fa.<\/p><\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"26\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Durante a confus\u00e3o, o suspeito esfaqueou o idoso&nbsp; tentou fugir, mas foi impedido por alguns moradores. O idoso n\u00e3o resistiu aos ferimentos e morreu no local. A pol\u00edcia militar foi acionada e levou o acusado para o hospital de Itacar\u00e9. O corpo do idoso ser\u00e1 encaminhado ao Departamento de Pol\u00edcia T\u00e9cnica em Ilh\u00e9us (DPT).&nbsp;<\/p>\n<div class=\"mc-column entities\">&nbsp;<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"40\" data-block-id=\"4\">&nbsp;<\/div>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"41\" data-block-id=\"2\">&nbsp;<\/div>\n<\/div>\n<\/div>\n<div class=\"medium-centered subtitle\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um idoso de 65 anos foi morto a facadas durante uma briga nesta ter\u00e7a-feira (26). O suspeito do assassinato foi linchado pela popula\u00e7\u00e3o que&nbsp; se revoltou com o crime. O caso ocorreu no povoado do Quitungo, na zona rural de Mara\u00fa. O idoso identificado por Valtemiro Paulo da Cruz, foi encontrado morto no sof\u00e1 por populares. Durante a confus\u00e3o, o suspeito esfaqueou o idoso&nbsp; tentou fugir, mas foi impedido por alguns moradores. O idoso n\u00e3o resistiu aos ferimentos e morreu no local. A pol\u00edcia militar foi acionada e levou o acusado para o hospital de Itacar\u00e9. O corpo do idoso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115830,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17,19],"tags":[817],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115829"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=115829"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115829\/revisions"}],"predecessor-version":[{"id":115834,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115829\/revisions\/115834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/115830"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=115829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=115829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=115829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}