{"id":115821,"date":"2019-02-26T21:31:37","date_gmt":"2019-02-27T00:31:37","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=115821"},"modified":"2019-02-26T21:46:09","modified_gmt":"2019-02-27T00:46:09","slug":"marau-estrutura-do-saquafolia-2019-comeca-a-ser-montada-em-saquaira","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/02\/26\/marau-estrutura-do-saquafolia-2019-comeca-a-ser-montada-em-saquaira\/","title":{"rendered":"Mara\u00fa: Estrutura do Saquafolia 2019 come\u00e7a a ser montada em Saqua\u00edra"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-115822 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-21.23.15-2.jpeg\" alt=\"\" width=\"557\" height=\"418\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-21.23.15-2.jpeg 1056w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-21.23.15-2-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-21.23.15-2-768x576.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-26-at-21.23.15-2-1024x768.jpeg 1024w\" sizes=\"(max-width: 557px) 100vw, 557px\" \/><\/p>\n<p>Come\u00e7ou na manh\u00e3 desta \u00faltima ter\u00e7a-feira, dia 26, a montagem do palco do carnaval de Saqua\u00edra, na Pen\u00ednsula de Mara\u00fa.&nbsp;A festa deve atrair muitos turistas para a regi\u00e3o de Saqua\u00edra que j\u00e1 est\u00e1 com a rede hoteleira praticamente lotada. O saquafolia como \u00e9 carinhosamente chamado, come\u00e7a no s\u00e1bado e vai at\u00e9 a segunda-feira.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Funcion\u00e1rios da Secretaria de Infraestrutura e Obras da Prefeitura de Mara\u00fa, est\u00e3o no povoado fazendo a limpeza e melhorando a ilumina\u00e7\u00e3o das ruas.&nbsp;Al\u00e9m do palco, ser\u00e3o instaladas no circuito da folia, barracas para ambulantes e banheiros qu\u00edmicos. A seguran\u00e7a ser\u00e1 feita pela Pol\u00edcia Militar e Pol\u00edcia Civil. A equipe da infraestrutura est\u00e1 sendo acompanhada de perto pelo administrador do povoado, Ant\u00f4nio Tipinha.<\/p>\n<p>&nbsp;<\/p>\n<p>As atra\u00e7\u00f5es que v\u00e3o animar os foli\u00f5es ser\u00e3o: Vitrine do Amor, Mandrakes, Boyzinho, Turma da Katuaba, Magnatas da Bregadeira, Pirilampo, S4 &amp; Cia, Via de Acesso e Jeane Lima. Al\u00e9m das bandas, o pared\u00e3o &#8220;Quem bota \u00e9 noix&#8221; vai agitar tamb\u00e9m a galera.<\/p>\n<p>De acordo com a prefeita, a festa est\u00e1 sendo feita dentro das condi\u00e7\u00f5es financeiras do munic\u00edpio, pois trata-se de uma manifesta\u00e7\u00e3o cultural de todo o pa\u00eds. \u201cAl\u00e9m de fazer a alegria da maioria da popula\u00e7\u00e3o, traz retorno financeiro para a cidade, fomentando o turismo e o com\u00e9rcio local\u201d, afirmou a prefeita. O evento \u00e9 organizado pela Prefeitura, atrav\u00e9s da secretaria de Turismo e Lazer com o apoio da Bahiatursa.<\/p>\n<p style=\"text-align: center;\"><strong>ASCOM \u2013 Prefeitura Municipal de Mara\u00fa<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7ou na manh\u00e3 desta \u00faltima ter\u00e7a-feira, dia 26, a montagem do palco do carnaval de Saqua\u00edra, na Pen\u00ednsula de Mara\u00fa.&nbsp;A festa deve atrair muitos turistas para a regi\u00e3o de Saqua\u00edra que j\u00e1 est\u00e1 com a rede hoteleira praticamente lotada. O saquafolia como \u00e9 carinhosamente chamado, come\u00e7a no s\u00e1bado e vai at\u00e9 a segunda-feira.&nbsp; &nbsp; Funcion\u00e1rios da Secretaria de Infraestrutura e Obras da Prefeitura de Mara\u00fa, est\u00e3o no povoado fazendo a limpeza e melhorando a ilumina\u00e7\u00e3o das ruas.&nbsp;Al\u00e9m do palco, ser\u00e3o instaladas no circuito da folia, barracas para ambulantes e banheiros qu\u00edmicos. A seguran\u00e7a ser\u00e1 feita pela Pol\u00edcia Militar e Pol\u00edcia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,26,29,17,18,27,28,11],"tags":[816],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115821"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=115821"}],"version-history":[{"count":3,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115821\/revisions"}],"predecessor-version":[{"id":115828,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115821\/revisions\/115828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/115822"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=115821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=115821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=115821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}