{"id":115473,"date":"2019-01-26T18:34:45","date_gmt":"2019-01-26T21:34:45","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=115473"},"modified":"2019-01-26T18:35:49","modified_gmt":"2019-01-26T21:35:49","slug":"governo-da-bahia-investe-quase-3-milhoes-na-construcao-do-colegio-estadual-de-barra-grande-que-entra-na-fase-final","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/01\/26\/governo-da-bahia-investe-quase-3-milhoes-na-construcao-do-colegio-estadual-de-barra-grande-que-entra-na-fase-final\/","title":{"rendered":"Governo da Bahia investe quase 3 milh\u00f5es na constru\u00e7\u00e3o do col\u00e9gio estadual de Barra Grande que entra na fase final\u00a0"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-115473 gallery-columns-3 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.02.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"576\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.02-1024x576.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.02-1024x576.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.02-300x169.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.02-768x432.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.02.jpeg 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.41.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"576\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.41-1024x576.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.41-1024x576.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.41-300x169.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.41-768x432.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.27.41.jpeg 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"576\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1-1024x576.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1-1024x576.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1-300x169.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1-768x432.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1.jpeg 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"576\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1024x576.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-1024x576.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-300x169.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33-768x432.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.33.jpeg 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.15.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"768\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.15-1024x768.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-115479\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.15-1024x768.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.15-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.15-768x576.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.15.jpeg 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-115479'>\n\t\t\t\tLaborat\u00f3rio de Qu\u00edmica\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.02.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"576\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.02-1024x576.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.02-1024x576.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.02-300x169.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.02-768x432.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.25.02.jpeg 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"767\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1024x767.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1024x767.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-768x575.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-2.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"665\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-2-1024x665.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-2-1024x665.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-2-300x195.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-2-768x499.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-2.jpeg 1046w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"634\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-1024x634.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-1024x634.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-300x186.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-768x475.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32.jpeg\" class=\"gallery_colorbox\"><img width=\"1024\" height=\"574\" src=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-1024x574.jpeg\"  class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-115474\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-1024x574.jpeg 1024w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-300x168.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-768x430.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-115474'>\n\t\t\t\tVereador Gustavo e a Secret\u00e1ria de Turismo Nilza.\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p><strong>MARA\u00da &#8211;<\/strong> A constru\u00e7\u00e3o do col\u00e9gio estadual de Barra Grande \u00e9 de fato o maior investimento j\u00e1 feito pelo Governo do Estado no munic\u00edpio.&nbsp;O valor do projeto para constru\u00e7\u00e3o da unidade escolar est\u00e1 estimado em cerca de R$ 2,9 milh\u00f5es e a empresa que venceu o processo licitat\u00f3rio, a T&amp;F Constru\u00e7\u00f5es e Empreendimentos Ltda, est\u00e1 trabalhando com uma grande equipe para ultimar os servi\u00e7os.&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Governo da Bahia investe quase 3 milh\u00f5es na constru\u00e7\u00e3o do col\u00e9gio de Barra Grande\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Nht-dXMQFE8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>O col\u00e9gio ter\u00e1 uma estrutura com tr\u00eas salas de aula, refeit\u00f3rio, sala de inform\u00e1tica, laborat\u00f3rio de ci\u00eancias, quadra poliesportiva, biblioteca, guarita, estacionamento, sala dos professores, sala da dire\u00e7\u00e3o, vice-dire\u00e7\u00e3o e da coordena\u00e7\u00e3o. Al\u00e9m dos estudantes de Barra Grande, o novo col\u00e9gio tamb\u00e9m ir\u00e1 beneficiar os alunos de Taipu de Fora, Taipu de Dentro, Campinho e da Ilha do Sapinho.&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-115477 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23.jpeg\" alt=\"\" width=\"596\" height=\"447\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23.jpeg 1280w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-768x575.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1024x767.jpeg 1024w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/p>\n<p>Todo esse investimento \u00e9 gra\u00e7as as cobran\u00e7as feitas pela Prefeita Gracinha Viana aos Deputados Eduardo Salles e Ronaldo Carletto que n\u00e3o mediram esfor\u00e7os para cobrar do Governador Rui Costa a realiza\u00e7\u00e3o desse mega investimento na educa\u00e7\u00e3o do munic\u00edpio. Gracinha que j\u00e1 esteve no local para acompanhar o andamento da obra comentou sobre a constru\u00e7\u00e3o.&nbsp;<em>\u201cTeremos uma escola de qualidade e com toda infraestrutura para que a gente possa melhorar a condi\u00e7\u00f5es de ensino para os alunos de Barra Grande e povoados circunvizinhos\u201d<\/em>, afirmou.<\/p>\n<div id=\"attachment_115474\" style=\"width: 606px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-115474\" loading=\"lazy\" class=\" wp-image-115474\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32.jpeg\" alt=\"\" width=\"596\" height=\"334\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32.jpeg 1280w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-300x168.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-768x430.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.23.32-1024x574.jpeg 1024w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><p id=\"caption-attachment-115474\" class=\"wp-caption-text\">Vereador Gustavo e a Secret\u00e1ria de Turismo Nilza.<\/p><\/div>\n<p>O Vereador Gustavo Magalh\u00e3es esteve tamb\u00e9m nesta semana juntamente com a Secret\u00e1ria de Turismo, Nilza Vicente e ficaram encantados com a estrutura que est\u00e1 sendo feita para os alunos. O col\u00e9gio deve ser entregue em mar\u00e7o e a previs\u00e3o \u00e9 de que o Governador Rui Costa inaugure a unidade.&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-115475 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1.jpeg\" alt=\"\" width=\"595\" height=\"368\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1.jpeg 1280w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-300x186.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-768x475.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-26-at-18.24.23-1-1024x634.jpeg 1024w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARA\u00da &#8211; A constru\u00e7\u00e3o do col\u00e9gio estadual de Barra Grande \u00e9 de fato o maior investimento j\u00e1 feito pelo Governo do Estado no munic\u00edpio.&nbsp;O valor do projeto para constru\u00e7\u00e3o da unidade escolar est\u00e1 estimado em cerca de R$ 2,9 milh\u00f5es e a empresa que venceu o processo licitat\u00f3rio, a T&amp;F Constru\u00e7\u00f5es e Empreendimentos Ltda, est\u00e1 trabalhando com uma grande equipe para ultimar os servi\u00e7os.&nbsp; O col\u00e9gio ter\u00e1 uma estrutura com tr\u00eas salas de aula, refeit\u00f3rio, sala de inform\u00e1tica, laborat\u00f3rio de ci\u00eancias, quadra poliesportiva, biblioteca, guarita, estacionamento, sala dos professores, sala da dire\u00e7\u00e3o, vice-dire\u00e7\u00e3o e da coordena\u00e7\u00e3o. Al\u00e9m dos estudantes de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115476,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,26,29,17,18],"tags":[700],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115473"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=115473"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115473\/revisions"}],"predecessor-version":[{"id":115485,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115473\/revisions\/115485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/115476"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=115473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=115473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=115473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}