{"id":115416,"date":"2019-01-24T20:12:07","date_gmt":"2019-01-24T23:12:07","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=115416"},"modified":"2019-01-24T20:12:07","modified_gmt":"2019-01-24T23:12:07","slug":"convenio-entre-policia-militar-e-prefeitura-de-marau-levara-ensino-militar-aos-colegios-de-barra-grande-e-tremembe","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2019\/01\/24\/convenio-entre-policia-militar-e-prefeitura-de-marau-levara-ensino-militar-aos-colegios-de-barra-grande-e-tremembe\/","title":{"rendered":"Conv\u00eanio entre Pol\u00edcia Militar e Prefeitura de Mara\u00fa levar\u00e1 ensino militar aos col\u00e9gios de Barra Grande e Trememb\u00e9"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"wp-image-115423 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-24-at-19.06.12-1.jpeg\" alt=\"\" width=\"596\" height=\"447\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-24-at-19.06.12-1.jpeg 1280w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-24-at-19.06.12-1-300x225.jpeg 300w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-24-at-19.06.12-1-768x576.jpeg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2019\/01\/WhatsApp-Image-2019-01-24-at-19.06.12-1-1024x768.jpeg 1024w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/p>\n<p>Na cerim\u00f4nia de reinaugura\u00e7\u00e3o do posto policial no povoado do Caubi, o comandante geral da pol\u00edcia militar da Bahia, Coronel Anselmo Brand\u00e3o, prop\u00f4s a implanta\u00e7\u00e3o da metodologia educacional dos Col\u00e9gios da Pol\u00edcia Militar (CPMs) em escolas de Mara\u00fa.&nbsp;A prefeita Gracinha Viana agradeceu e aceitou a proposta do comandante e disse que em breve, pretende levar o ensino militar para os col\u00e9gios do povoado de Trememb\u00e9 e do Distrito de Barra Grande.<\/p>\n<p style=\"font-weight: 400;\">Em sua fala, o comandante afirmou que o acordo permitir\u00e1 a PM\/BA \u201ctransferir seu modelo para as escolas p\u00fablicas de Mara\u00fa, sem a necess\u00e1ria militariza\u00e7\u00e3o da unidade, apenas com a incorpora\u00e7\u00e3o de uma cultura que busca o desenvolvimento progressivo do estudante\u201d. O coronel tamb\u00e9m ressaltou que a PM criou um modelo de gest\u00e3o de excel\u00eancia para seus col\u00e9gios, que est\u00e3o inclu\u00eddos entre as 10 melhores escolas do estado em avalia\u00e7\u00f5es do Minist\u00e9rio da Educa\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na cerim\u00f4nia de reinaugura\u00e7\u00e3o do posto policial no povoado do Caubi, o comandante geral da pol\u00edcia militar da Bahia, Coronel Anselmo Brand\u00e3o, prop\u00f4s a implanta\u00e7\u00e3o da metodologia educacional dos Col\u00e9gios da Pol\u00edcia Militar (CPMs) em escolas de Mara\u00fa.&nbsp;A prefeita Gracinha Viana agradeceu e aceitou a proposta do comandante e disse que em breve, pretende levar o ensino militar para os col\u00e9gios do povoado de Trememb\u00e9 e do Distrito de Barra Grande. Em sua fala, o comandante afirmou que o acordo permitir\u00e1 a PM\/BA \u201ctransferir seu modelo para as escolas p\u00fablicas de Mara\u00fa, sem a necess\u00e1ria militariza\u00e7\u00e3o da unidade, apenas com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115423,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,26,29,17,18,1,28],"tags":[694],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115416"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=115416"}],"version-history":[{"count":2,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115416\/revisions"}],"predecessor-version":[{"id":115424,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115416\/revisions\/115424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/115423"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=115416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=115416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=115416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}