{"id":115083,"date":"2018-12-13T09:02:06","date_gmt":"2018-12-13T12:02:06","guid":{"rendered":"http:\/\/www.barragrande24horas.com.br\/v1\/?p=115083"},"modified":"2018-12-13T09:02:06","modified_gmt":"2018-12-13T12:02:06","slug":"leiturista-tem-moto-roubada-enquanto-trabalhava-na-br-030-em-marau-proximo-ao-povoado-de-sao-raimundo","status":"publish","type":"post","link":"https:\/\/www.barragrande24horas.com.br\/v1\/2018\/12\/13\/leiturista-tem-moto-roubada-enquanto-trabalhava-na-br-030-em-marau-proximo-ao-povoado-de-sao-raimundo\/","title":{"rendered":"Leiturista tem moto roubada enquanto trabalhava na BR 030 em Mara\u00fa, pr\u00f3ximo ao povoado de S\u00e3o Raimundo"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-115084 aligncenter\" src=\"http:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2018\/12\/cor_01_2.jpg\" alt=\"\" width=\"594\" height=\"356\" srcset=\"https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2018\/12\/cor_01_2.jpg 768w, https:\/\/www.barragrande24horas.com.br\/v1\/wp-content\/uploads\/2018\/12\/cor_01_2-300x180.jpg 300w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/><\/p>\n<p>Os bandidos tomaram de assalto uma motocicleta Honda Broz 160, de cor preta e placa PKX 6605, que \u00e9 da empresa Emgelming, prestadora de servi\u00e7o da Coelba, na manh\u00e3 da \u00faltima quarta-feira (12), na BR 030, entre as localidades de Belmiro e o povoado de S\u00e3o Raimundo, em Mara\u00fa.&nbsp;A v\u00edtima relatou que trabalha para uma empresa que presta servi\u00e7o para a COELBA e que estava realizando a leitura de energia das localidades e quando trafegava pela BR 030, foi surpreendido por tr\u00eas elementos em um ve\u00edculo Fiat Uno, sendo que dois deles estavam armados, e anunciaram o assalto. Ap\u00f3s o ocorrido, buscas foram&nbsp; feitas, mas o ve\u00edculo e o assaltante n\u00e3o foram encontrados. Qualquer informa\u00e7\u00e3o deve ser passada atrav\u00e9s do telefone 73 98211 2363.<\/p>\n<div class=\"teads-inread teads-display-format sm-screen\">\n<div class=\"teads-ui-components-adchoices\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"teads-ui-components-label\">&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os bandidos tomaram de assalto uma motocicleta Honda Broz 160, de cor preta e placa PKX 6605, que \u00e9 da empresa Emgelming, prestadora de servi\u00e7o da Coelba, na manh\u00e3 da \u00faltima quarta-feira (12), na BR 030, entre as localidades de Belmiro e o povoado de S\u00e3o Raimundo, em Mara\u00fa.&nbsp;A v\u00edtima relatou que trabalha para uma empresa que presta servi\u00e7o para a COELBA e que estava realizando a leitura de energia das localidades e quando trafegava pela BR 030, foi surpreendido por tr\u00eas elementos em um ve\u00edculo Fiat Uno, sendo que dois deles estavam armados, e anunciaram o assalto. Ap\u00f3s o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115084,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,29,17,20,27,3],"tags":[587,588],"_links":{"self":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115083"}],"collection":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/comments?post=115083"}],"version-history":[{"count":1,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115083\/revisions"}],"predecessor-version":[{"id":115085,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/posts\/115083\/revisions\/115085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media\/115084"}],"wp:attachment":[{"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/media?parent=115083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/categories?post=115083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barragrande24horas.com.br\/v1\/wp-json\/wp\/v2\/tags?post=115083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}